{"id":54913,"date":"2020-11-20T16:53:52","date_gmt":"2020-11-20T19:53:52","guid":{"rendered":"https:\/\/webdelmaestrocmf.com\/portal\/?p=54913"},"modified":"2020-11-26T18:02:27","modified_gmt":"2020-11-26T21:02:27","slug":"como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias","status":"publish","type":"post","link":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/","title":{"rendered":"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral. El exceso de videollamadas es un nuevo factor de agotamiento f\u00edsico, psicol\u00f3gico y emocional. C\u00f3mo superar la adicci\u00f3n de jefes, equipos y empresas a las videoconferencias.<\/h5>\n<p><!--more--><\/p>\n<h5 style=\"text-align: justify;\">La\u00a0pandemia por\u00a0coronavirus\u00a0oblig\u00f3 a las organizaciones a adaptarse r\u00e1pidamente.\u00a0<strong>El\u00a0teletrabajo\u00a0o home\u00a0office\u00a0surgi\u00f3 como alternativa v\u00e1lida para continuar con el &#8216;business\u00a0as usual&#8217;.<\/strong>\u00a0Muchas empresas no estaban acostumbradas a esta modalidad y tuvieron que capacitar a sus colaboradores en forma remota para<strong> incorporar esta\u00a0nueva realidad potenciando su impacto en t\u00e9rminos de\u00a0eficiencia y motivaci\u00f3n&#8230;\u00a0Pero no siempre sucede. Y el culpable es Zoom.<\/strong><\/h5>\n<p style=\"text-align: justify;\"><strong>Pero esta modalidad, luego de varios meses,\u00a0comenz\u00f3 a generar ansiedad, estr\u00e9s e incluso su expresi\u00f3n m\u00e1s extrema: el burn out. Y\u00a0la responsable es la adicci\u00f3n de l\u00edderes, equipos y empresas a la comunicaci\u00f3n por\u00a0videollamadas.<\/strong><\/p>\n<p style=\"text-align: justify;\">La escena se repite:\u00a0<strong>faltan pocos minutos para esa nueva videollamada que figura en la agenda.<\/strong>\u00a0\u00bfC\u00f3mo pas\u00f3 tan r\u00e1pido el tiempo? Quedan varias cosas por terminar antes de entrar a esa reuni\u00f3n<strong>\u00a0que, adem\u00e1s, no se sabe cu\u00e1nto puede llegar a durar ni queda muy claro qu\u00e9 temas se van a abordar<\/strong>. Uno se peina un poco, ordena el lugar, pide silencio a la familia, se prepara un caf\u00e9 o un mate.\u00a0<strong>La ansiedad aumenta y uno\u00a0se resigna a entrar a la sala de reuni\u00f3n virtual&#8230;<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-54918\" src=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2.jpg\" alt=\"\" width=\"1100\" height=\"574\" srcset=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2.jpg 1100w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-300x157.jpg 300w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-1024x534.jpg 1024w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-768x401.jpg 768w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-110x57.jpg 110w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-200x104.jpg 200w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-380x198.jpg 380w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-255x133.jpg 255w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-550x287.jpg 550w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-800x417.jpg 800w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-220x115.jpg 220w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-400x209.jpg 400w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-760x397.jpg 760w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-510x266.jpg 510w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd2-600x313.jpg 600w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Sumarse a esos encuentros puede ser estresante, m\u00e1s a\u00fan si son varios por semana o uno detr\u00e1s de otro.<\/strong>\u00a0Por eso, muchos especialistas en coaching y bienestar laboral ya hablan del\u00a0<strong>s\u00edndrome de\u00a0burn\u00a0out\u00a0de\u00a0videochat, mientras que otros lo llaman fatiga del Zoom.<\/strong><\/p>\n<p style=\"text-align: justify;\">Pero, \u00bf qu\u00e9 es lo que realmente nos incomoda de esta forma de comunicaci\u00f3n e interacci\u00f3n? Sara Mendoza Figueroa, gerente de Marketing de VISMA Latinoam\u00e9rica, revela\u00a0<strong>10\u00a0buenas pr\u00e1cticas para\u00a0aliviar el desgaste f\u00edsico, psicol\u00f3gico y emocional que generan el exceso de\u00a0videoconferencias.<\/strong><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/eaC0qXwdn_M\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h5 style=\"text-align: justify;\">1. HACER REGISTRO<\/h5>\n<p style=\"text-align: justify;\"><strong>Anotar cu\u00e1ntas videollamadas\u00a0tuviste en la\u00a0semana, cu\u00e1nto tiempo demand\u00f3 cada una y qu\u00e9 te\u00a0incomod\u00f3\u00a0de cada una de ellas\u00a0<\/strong>(si estar frente a la c\u00e1mara, si son muy seguidas o largas, si no contribuyen a avanzar con tu\u00a0trabajo). Vale incluir tambi\u00e9n las reuniones virtuales sociales (after office, saludo de cumplea\u00f1os). El objetivo es identificar cu\u00e1l es tu reacci\u00f3n ante las videollamadas para distinguir qu\u00e9 te pasa cuando son laborales o personales.<\/p>\n<h5 style=\"text-align: justify;\">2. LIMITAR LAS VIDEOLLAMADAS<\/h5>\n<p style=\"text-align: justify;\">Los expertos en bienestar laboral coinciden en la importancia de\u00a0<strong>limitar las reuniones virtuales a las estrictamente necesarias e invitar a participar \u00fanicamente a las personas pertinentes<\/strong>. \u00bfCu\u00e1les de esas charlas se pueden abordar mejor a trav\u00e9s de un mail, de una llamada telef\u00f3nica o un documento compartido en el que se puedan agregar notas claras para trabajarlo en equipo?<\/p>\n<h5 style=\"text-align: justify;\">3. DEFINIR ESTRUCTURA, HORARIOS Y DURACI\u00d3N<\/h5>\n<p style=\"text-align: justify;\"><strong>Lo ideal son reuniones de media hora a una hora como m\u00e1ximo<\/strong>. Adem\u00e1s, se recomienda evitar hacerlas despu\u00e9s de las 18, y los viernes hasta las 15. El protocolo es igual que con las reuniones presenciales:\u00a0preparar con antelaci\u00f3n los objetivos de los encuentros para que los participantes sepan con precisi\u00f3n qu\u00e9 se espera lograr en y de cada uno.<\/p>\n<h5 style=\"text-align: justify;\">4. DISPONERSE CON EMPAT\u00cdA<\/h5>\n<p style=\"text-align: justify;\">Antes de ir al tema central de la reuni\u00f3n,\u00a0<strong>saludar, preguntar al otro c\u00f3mo est\u00e1<\/strong>, c\u00f3mo se siente en este contexto, si pas\u00f3 algo relevante fuera del \u00e1mbito laboral. Se trata de saber m\u00e1s del otro, tambi\u00e9n contar las propias situaciones, y as\u00ed estrechar lazos de confianza. Esto prepara\u00a0el terreno para\u00a0<strong>tener una conversaci\u00f3n laboral m\u00e1s distendida y genuina<\/strong>.<\/p>\n<h5 style=\"text-align: justify;\">5. HABLAR S\u00d3LO SI APORTA VALOR<\/h5>\n<p style=\"text-align: justify;\">Antes de intervenir, es importante preguntarse\u00a0\u201ccu\u00e1l es el aporte de que diga lo que estoy pensando\u201d. La idea es\u00a0<strong>que cada comentario sea verdaderamente relevante<\/strong>, para ayudar a que las conversaciones vayan siempre al foco.<\/p>\n<h5 style=\"text-align: justify;\">6. CUBRIR LA PROPIA IMAGEN<\/h5>\n<p style=\"text-align: justify;\"><strong>Verse a uno mismo en la pantalla es factor de distracci\u00f3n.<\/strong>\u00a0Algunos expertos sugieren prender la c\u00e1mara s\u00f3lo cuando sea necesario\u00a0si el protocolo de la reuni\u00f3n\/organizaci\u00f3n da la posibilidad. Es conveniente desplazar la propia imagen hacia un extremo de la pantalla o reducirla o taparla con un post-it y tomar notas para concentrar la vista en otro lado.<\/p>\n<h5 style=\"text-align: justify;\">7. EVITAR EL MULTITASKING<\/h5>\n<p style=\"text-align: justify;\">Cuando llegue la hora de la videollamada, enfocarse s\u00f3lo en ella.\u00a0<strong>Tratar de estar pendiente de varias actividades en simult\u00e1neo provoca agotamiento, e incluso podr\u00eda parecer que no se tiene inter\u00e9s en la reuni\u00f3n.<\/strong>\u00a0Una manera de sentirse m\u00e1s productivo y reducir el estr\u00e9s podr\u00eda ser, por ejemplo, dedicar las ma\u00f1anas a las tareas habituales del trabajo y las tardes a las videollamadas y reuniones virtuales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-54917\" src=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd.jpg\" alt=\"\" width=\"1100\" height=\"574\" srcset=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd.jpg 1100w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-300x157.jpg 300w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-1024x534.jpg 1024w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-768x401.jpg 768w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-110x57.jpg 110w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-200x104.jpg 200w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-380x198.jpg 380w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-255x133.jpg 255w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-550x287.jpg 550w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-800x417.jpg 800w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-220x115.jpg 220w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-400x209.jpg 400w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-760x397.jpg 760w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-510x266.jpg 510w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/banner-facebookpsd-600x313.jpg 600w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<h5 style=\"text-align: justify;\">8. RECAPITULAR<\/h5>\n<p style=\"text-align: justify;\">Enviar un resumen de los temas tratados y las conclusiones por mail a todos los participantes. Es una forma de\u00a0<strong>\u201cestar todos en la misma p\u00e1gina\u201d<\/strong>, evitar confusiones o reiterar temas ya conversados a futuro.<\/p>\n<h5 style=\"text-align: justify;\">9. HACER UN BREAK<\/h5>\n<p style=\"text-align: justify;\">Entre una y otra videollamada es conveniente levantarse de la silla, caminar por la casa,\u00a0<strong>hacerse un caf\u00e9, escuchar m\u00fasica o radio, hacer alg\u00fan ejercicio.<\/strong>\u00a0Desconectar un poco es clave para retomar las tareas con eficiencia.<\/p>\n<h5 style=\"text-align: justify;\">10. ESTABLECER Y MANTENER UNA RUTINA<\/h5>\n<p style=\"text-align: justify;\">Es importante tratar de\u00a0<strong>acostarse y levantarse a la misma hora todos los d\u00edas<\/strong>, determinar un horario de trabajo y as\u00ed crear un h\u00e1bito que contribuya a un biorritmo propio durante la pandemia. Tener un\u00a0horario fijo de inicio y finalizaci\u00f3n es vital para\u00a0hacer otras cosas:\u00a0hablar con amigos, estar con la familia, estudiar, mirar una pel\u00edcula. Tambi\u00e9n ayuda\u00a0<strong>hacer las comidas lejos de las pantallas o del smartphone<\/strong>, sin distracciones. Un momento para cada cosa y cada cosa en su lugar ayudan a disminuir el estr\u00e9s.<\/p>\n<p><strong>Este contenido ha sido publicado originalmente por El Cronista en la siguiente direcci\u00f3n: <a href=\"http:\/\/cronista.com\" target=\"_blank\" rel=\"noopener noreferrer\">cronista.com<\/a><\/strong><\/p>\n\t\t<div class=\"pk-inline-posts\">\n\t\t\t\n\t\t\t<div class=\"pk-inline-posts-container pk-inline-posts-template-list\"\n\t\t\t\tdata-columns=\"1\">\n\t\t\t\t\t\t<article id=\"post-120142\" class=\"post-120142 post type-post status-publish format-standard has-post-thumbnail category-descarga category-pedagogia category-software category-tecnologia tag-ahorro-docente tag-canva-en-el-aula tag-decoracion-escolar tag-estrategias-de-ensenanza tag-herramientas-digitales-gratuitas tag-innovacion-educativa-2 tag-material-didactico-impreso tag-murales-para-clases tag-recursos-para-docentes cs-entry cs-video-wrap\">\n\t\t\t<div class=\"pk-post-outer\">\n\n\t\t\t\t\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<div class=\"entry-thumbnail\">\n\t\t\t\t\t\t<div class=\"pk-overlay pk-overlay-ratio pk-ratio-landscape\">\n\t\t\t\t\t\t\t<div class=\"pk-overlay-background\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/webdelmaestrocmf.com\/portal\/como-crear-carteles-gigantes-para-tu-aula-con-una-impresora-normal-descarga-la-guia-pdf\/\" class=\"pk-overlay-link\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2026\/06\/1AA-Banner-1-portada-imagen-10-1-copia-2-2-300x225.webp\" class=\"attachment-pk-thumbnail size-pk-thumbnail wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<header>\n\t\t\t\t\t\t<h3 class=\"pk-title\"><a href=\"https:\/\/webdelmaestrocmf.com\/portal\/como-crear-carteles-gigantes-para-tu-aula-con-una-impresora-normal-descarga-la-guia-pdf\/\" rel=\"bookmark\">C\u00f3mo crear carteles gigantes para tu aula con una impresora normal: Descarga la gu\u00eda PDF<\/a><\/h3>\t\t\t\t\t<\/header><!-- .entry-header -->\n\t\t\t\t<\/div><!-- .post-inner -->\n\n\t\t\t<\/div><!-- .post-outer -->\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral.&hellip;","protected":false},"author":1,"featured_media":54916,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"csco_display_header_overlay":false,"csco_singular_sidebar":"default","csco_page_header_type":"default","csco_page_load_nextpost":"default","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"csco_post_video_bg_volume":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1648,737],"tags":[6078,682,712,4512,4952],"class_list":["post-54913","post","type-post","status-publish","format-standard","has-post-thumbnail","category-software","category-tecnologia","tag-cansancio","tag-estres","tag-evitar","tag-tantas","tag-videoconferencias","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias - 2026<\/title>\n<meta name=\"description\" content=\"Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral. El exceso de videollamadas...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias - 2026\" \/>\n<meta property=\"og:description\" content=\"Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral. El exceso de videollamadas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/\" \/>\n<meta property=\"og:site_name\" content=\"Web del Maestro CMF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WebdelMaestroCMF\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/WebdelMaestroCMF\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-20T19:53:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-26T21:02:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/1a-6.jpg?fit=1100%2C680&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Web del Maestro CMF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cmf_w\" \/>\n<meta name=\"twitter:site\" content=\"@cmf_w\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ScholarlyArticle\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/\"},\"author\":{\"name\":\"Web del Maestro CMF\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/person\\\/1072a2ed7bd960df8ef99a551fa35dc5\"},\"headline\":\"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias\",\"datePublished\":\"2020-11-20T19:53:52+00:00\",\"dateModified\":\"2020-11-26T21:02:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/\"},\"wordCount\":1040,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1a-6.jpg\",\"keywords\":[\"cansancio\",\"ESTR\u00c9S\",\"EVITAR\",\"tantas\",\"videoconferencias\"],\"articleSection\":[\"Software\",\"Tecnolog\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/\",\"name\":\"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias - 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1a-6.jpg\",\"datePublished\":\"2020-11-20T19:53:52+00:00\",\"dateModified\":\"2020-11-26T21:02:27+00:00\",\"description\":\"Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral. El exceso de videollamadas...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1a-6.jpg\",\"contentUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1a-6.jpg\",\"width\":1100,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnolog\u00eda\",\"item\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/category\\\/tecnologia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Software\",\"item\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/category\\\/tecnologia\\\/software\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/\",\"name\":\"Web del Maestro CMF\",\"description\":\"Maestros al servicio de la educaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#organization\"},\"alternateName\":\"WMCMF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#organization\",\"name\":\"Web del Maestro CMF\",\"alternateName\":\"WMCMF\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-wmcmf-2.png\",\"contentUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-wmcmf-2.png\",\"width\":200,\"height\":60,\"caption\":\"Web del Maestro CMF\"},\"image\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WebdelMaestroCMF\\\/\",\"https:\\\/\\\/x.com\\\/cmf_w\",\"https:\\\/\\\/www.pinterest.com\\\/WMCMF\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/web-del-maestro-cmf\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wmcmf\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDPSvjbdodE5sHnC3OxutHw\",\"https:\\\/\\\/mastodon.social\\\/@wmcmf\",\"https:\\\/\\\/www.tiktok.com\\\/@webdelmaestrocmf\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/person\\\/1072a2ed7bd960df8ef99a551fa35dc5\",\"name\":\"Web del Maestro CMF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g\",\"caption\":\"Web del Maestro CMF\"},\"description\":\"Esta Web se cre\u00f3 sin fines de lucro, con fines educativos, cient\u00edficos y acad\u00e9micos, para personas que tengan dificultades y\\\/o inconvenientes en visualizar el material original. El objetivo es entregar recursos, compartir experiencias y materiales que ayuden a los padres de familia, maestros y estudiantes en su actualizaci\u00f3n y formaci\u00f3n permanente, en bien de la Educaci\u00f3n.\",\"sameAs\":[\"http:\\\/\\\/webdelmaestrocmf.com\\\/portal\",\"https:\\\/\\\/www.facebook.com\\\/WebdelMaestroCMF\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wmcmf\\\/\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/web-del-maestro-cmf\",\"https:\\\/\\\/www.pinterest.com\\\/WMCMF\\\/publicaciones\\\/\",\"https:\\\/\\\/x.com\\\/cmf_w\",\"https:\\\/\\\/www.youtube.com\\\/@WMCMF\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias - 2026","description":"Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral. El exceso de videollamadas...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias - 2026","og_description":"Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral. El exceso de videollamadas...","og_url":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/","og_site_name":"Web del Maestro CMF","article_publisher":"https:\/\/www.facebook.com\/WebdelMaestroCMF\/","article_author":"https:\/\/www.facebook.com\/WebdelMaestroCMF\/","article_published_time":"2020-11-20T19:53:52+00:00","article_modified_time":"2020-11-26T21:02:27+00:00","og_image":[{"width":1100,"height":680,"url":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/1a-6.jpg?fit=1100%2C680&ssl=1","type":"image\/jpeg"}],"author":"Web del Maestro CMF","twitter_card":"summary_large_image","twitter_creator":"@cmf_w","twitter_site":"@cmf_w","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ScholarlyArticle","@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#article","isPartOf":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/"},"author":{"name":"Web del Maestro CMF","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/person\/1072a2ed7bd960df8ef99a551fa35dc5"},"headline":"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias","datePublished":"2020-11-20T19:53:52+00:00","dateModified":"2020-11-26T21:02:27+00:00","mainEntityOfPage":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/"},"wordCount":1040,"commentCount":2,"publisher":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#organization"},"image":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/1a-6.jpg","keywords":["cansancio","ESTR\u00c9S","EVITAR","tantas","videoconferencias"],"articleSection":["Software","Tecnolog\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/","url":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/","name":"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias - 2026","isPartOf":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#primaryimage"},"image":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/1a-6.jpg","datePublished":"2020-11-20T19:53:52+00:00","dateModified":"2020-11-26T21:02:27+00:00","description":"Burn out de videochat o fatiga de Zoom. El home office y teletrabajo en pandemia causa estr\u00e9s laboral. El exceso de videollamadas...","breadcrumb":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#primaryimage","url":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/1a-6.jpg","contentUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/1a-6.jpg","width":1100,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/webdelmaestrocmf.com\/portal\/como-evitar-el-cansancio-o-el-estres-con-tantas-videoconferencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/webdelmaestrocmf.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Tecnolog\u00eda","item":"https:\/\/webdelmaestrocmf.com\/portal\/category\/tecnologia\/"},{"@type":"ListItem","position":3,"name":"Software","item":"https:\/\/webdelmaestrocmf.com\/portal\/category\/tecnologia\/software\/"},{"@type":"ListItem","position":4,"name":"C\u00f3mo evitar el cansancio o el estr\u00e9s con tantas videoconferencias"}]},{"@type":"WebSite","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#website","url":"https:\/\/webdelmaestrocmf.com\/portal\/","name":"Web del Maestro CMF","description":"Maestros al servicio de la educaci\u00f3n","publisher":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#organization"},"alternateName":"WMCMF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/webdelmaestrocmf.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#organization","name":"Web del Maestro CMF","alternateName":"WMCMF","url":"https:\/\/webdelmaestrocmf.com\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/01\/logo-wmcmf-2.png","contentUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/01\/logo-wmcmf-2.png","width":200,"height":60,"caption":"Web del Maestro CMF"},"image":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WebdelMaestroCMF\/","https:\/\/x.com\/cmf_w","https:\/\/www.pinterest.com\/WMCMF\/","https:\/\/www.linkedin.com\/company\/web-del-maestro-cmf\/","https:\/\/www.instagram.com\/wmcmf\/","https:\/\/www.youtube.com\/channel\/UCDPSvjbdodE5sHnC3OxutHw","https:\/\/mastodon.social\/@wmcmf","https:\/\/www.tiktok.com\/@webdelmaestrocmf"]},{"@type":"Person","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/person\/1072a2ed7bd960df8ef99a551fa35dc5","name":"Web del Maestro CMF","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g","caption":"Web del Maestro CMF"},"description":"Esta Web se cre\u00f3 sin fines de lucro, con fines educativos, cient\u00edficos y acad\u00e9micos, para personas que tengan dificultades y\/o inconvenientes en visualizar el material original. El objetivo es entregar recursos, compartir experiencias y materiales que ayuden a los padres de familia, maestros y estudiantes en su actualizaci\u00f3n y formaci\u00f3n permanente, en bien de la Educaci\u00f3n.","sameAs":["http:\/\/webdelmaestrocmf.com\/portal","https:\/\/www.facebook.com\/WebdelMaestroCMF\/","https:\/\/www.instagram.com\/wmcmf\/","https:\/\/cl.linkedin.com\/company\/web-del-maestro-cmf","https:\/\/www.pinterest.com\/WMCMF\/publicaciones\/","https:\/\/x.com\/cmf_w","https:\/\/www.youtube.com\/@WMCMF"]}]}},"jetpack_featured_media_url":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/11\/1a-6.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":62279,"url":"https:\/\/webdelmaestrocmf.com\/portal\/atencion-maestros-y-alumnos-usan-zoom-google-meet-o-teams-no-se-imaginan-lo-que-le-hace-las-videoconferencias-las-clases-online-y-las-reuniones-virtuales-a-sus-cerebros\/","url_meta":{"origin":54913,"position":0},"title":"Atenci\u00f3n maestros y alumnos: \u00bfUsan Zoom, Google Meet o Teams? No se imaginan lo que le hace las videoconferencias, las clases online y las reuniones virtuales a sus cerebros","author":"Web del Maestro CMF","date":"26 abril, 2021","format":false,"excerpt":"De video llamada en video llamada y tiro porque me toca. Acabar una y empezar otra. Desde que la pandemia irrumpiera en nuestras vidas, muchos profesionales se encuentran, casi a diario, con una concatenaci\u00f3n de reuniones virtuales que se acaban prolongando durante horas. Incluso los hay que se tienen que\u00a0bloquear\u2026","rel":"","context":"En \u00abSoftware\u00bb","block_context":{"text":"Software","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/tecnologia\/software\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/04\/1-44-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/04\/1-44-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/04\/1-44-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/04\/1-44-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/04\/1-44-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":65058,"url":"https:\/\/webdelmaestrocmf.com\/portal\/cuatro-consecuencias-de-la-fatiga-de-zoom-y-como-los-docentes-pueden-combatirla\/","url_meta":{"origin":54913,"position":1},"title":"Cuatro consecuencias de la Fatiga de Zoom y c\u00f3mo los docentes pueden combatirla","author":"Web del Maestro CMF","date":"11 julio, 2021","format":false,"excerpt":"El t\u00e9rmino burnout puede sonar familiar para estudiantes o profesionistas de \u201calto rendimiento.\u201d Gracias a la alta demanda de distanciamiento social debido a la pandemia, miles de instituciones se han visto obligadas a sustituir sus conferencias presenciales con sesiones virtuales en video a trav\u00e9s de plataformas digitales. Desde alumnos, profesionistas\u2026","rel":"","context":"En \u00abInformativo\u00bb","block_context":{"text":"Informativo","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/tecnologia\/informativo-tecnologia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/07\/1-74.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/07\/1-74.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/07\/1-74.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/07\/1-74.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/07\/1-74.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":73034,"url":"https:\/\/webdelmaestrocmf.com\/portal\/cuatro-consecuencias-de-la-fatiga-de-zoom-y-como-combatirla\/","url_meta":{"origin":54913,"position":2},"title":"Cuatro consecuencias de la Fatiga de Zoom y c\u00f3mo combatirla","author":"Web del Maestro CMF","date":"13 enero, 2022","format":false,"excerpt":"El t\u00e9rmino burnout puede sonar familiar para estudiantes o profesionistas de \u201calto rendimiento.\u201d Gracias a la alta demanda de distanciamiento social debido a la pandemia, miles de instituciones se han visto obligadas a sustituir sus conferencias presenciales con sesiones virtuales en video a trav\u00e9s de plataformas digitales. Desde alumnos, profesionistas\u2026","rel":"","context":"En \u00abSoftware\u00bb","block_context":{"text":"Software","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/tecnologia\/software\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/01\/1-73.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/01\/1-73.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/01\/1-73.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/01\/1-73.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/01\/1-73.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":50869,"url":"https:\/\/webdelmaestrocmf.com\/portal\/como-hacer-cursos-virtuales-o-reuniones-digitales-exitosas-y-productivas\/","url_meta":{"origin":54913,"position":3},"title":"C\u00f3mo hacer clases virtuales o reuniones exitosas y productivas","author":"Web del Maestro CMF","date":"3 septiembre, 2020","format":false,"excerpt":"El\u00a0trabajo remoto\u00a0lleg\u00f3 para quedarse, todos hemos experimentado en los \u00faltimos meses reuniones virtuales buenas, malas, excelentes y terribles. El nivel de satisfacci\u00f3n en estos intercambios digitales dentro de la\u00a0nueva normalidad\u00a0depende de muchos factores que van desde lo t\u00e9cnico hasta lo incontrolable. Como persona de negocios, seguramente has tenido y tendr\u00e1s\u2026","rel":"","context":"En \u00abInformativo\u00bb","block_context":{"text":"Informativo","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/tecnologia\/informativo-tecnologia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/09\/1-copia-8.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/09\/1-copia-8.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/09\/1-copia-8.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/09\/1-copia-8.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/09\/1-copia-8.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":52318,"url":"https:\/\/webdelmaestrocmf.com\/portal\/las-mujeres-tienen-una-triple-jornada-laboral-por-la-pandemia-home-office-labores-del-hogar-y-cuidado-de-los-hijos\/","url_meta":{"origin":54913,"position":4},"title":"Las mujeres tienen una triple jornada laboral por la pandemia: home office, labores del hogar y cuidado de los hijos","author":"Web del Maestro CMF","date":"1 octubre, 2020","format":false,"excerpt":"La pandemia por la COVID-19 trajo un fuerte impacto en el trabajo que realizan las mujeres, siempre se han dividido entre la casa, el trabajo y el cuidado de los hijos,\u00a0 pero ahora se vuelve m\u00e1s dif\u00edcil porque muchos consideran que el trabajo del hogar no es trabajo. Estamos jugando\u2026","rel":"","context":"En \u00abEstr\u00e9s\u00bb","block_context":{"text":"Estr\u00e9s","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/estres\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/10\/1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/10\/1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/10\/1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/10\/1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/10\/1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":63767,"url":"https:\/\/webdelmaestrocmf.com\/portal\/transforma-tu-camara-fotografica-canon-en-una-webcam-de-alta-calidad-para-zoom-meet-teams-y-otras\/","url_meta":{"origin":54913,"position":5},"title":"Transforma tu c\u00e1mara fotogr\u00e1fica Canon en una webcam de alta calidad para Zoom, Meet, Teams y otras","author":"Web del Maestro CMF","date":"6 junio, 2021","format":false,"excerpt":"Videollamadas y streaming en directo: ahora mejor que nunca. Convierte tu c\u00e1mara Canon en una webcam para disfrutar de una calidad de imagen profesional en tus videoconferencias. Participa en reuniones con compa\u00f1eros, charla con familiares y amigos, y con\u00e9ctate donde y cuando quieras, incluso mientras viajas. Descarga el software EOS\u2026","rel":"","context":"En \u00abSoftware\u00bb","block_context":{"text":"Software","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/tecnologia\/software\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/06\/1.jpg-4.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/06\/1.jpg-4.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/06\/1.jpg-4.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/06\/1.jpg-4.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/06\/1.jpg-4.png?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/posts\/54913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/comments?post=54913"}],"version-history":[{"count":0,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/posts\/54913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/media\/54916"}],"wp:attachment":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/media?parent=54913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/categories?post=54913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/tags?post=54913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}