{"id":36352,"date":"2020-02-18T18:30:08","date_gmt":"2020-02-18T21:30:08","guid":{"rendered":"http:\/\/webdelmaestrocmf.com\/portal\/?p=36352"},"modified":"2020-02-18T18:39:52","modified_gmt":"2020-02-18T21:39:52","slug":"experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos","status":"publish","type":"post","link":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/","title":{"rendered":"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar \u00abMagnetismo\u00bb a los ni\u00f1os"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Los<strong>\u00a0experimentos infantiles<\/strong> permiten a los ni\u00f1os aprender jugando. Por eso, nunca nos cansamos de presentar nuevos <strong>experimentos para ni\u00f1os<\/strong>\u2026 Hoy <strong>con magnetismo. <\/strong>S\u00ed, como leen, los invitamos a experimentar con magnetos. Ver\u00e1s que a los peque\u00f1os les encantan estos <strong>experimentos<\/strong>, aprenden y se lo pasan muy bien.<\/h5>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">El magnetismo es uno de los elementos que m\u00e1s magia tiene a los ojos de los ni\u00f1os. Este puede ser un buen punto de partida para<strong>\u00a0hacer experimentos con imanes<\/strong>\u00a0con los que se diviertan y aprendan c\u00f3mo reaccionan los polos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44449\" src=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109.jpg\" alt=\"\" width=\"1100\" height=\"680\" srcset=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109.jpg 1100w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-300x185.jpg 300w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-1024x633.jpg 1024w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-768x475.jpg 768w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-110x68.jpg 110w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-200x124.jpg 200w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-380x235.jpg 380w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-255x158.jpg 255w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-550x340.jpg 550w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-109-800x495.jpg 800w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n compartimos con fines educativos los contenidos de los siguientes portales (<a href=\"http:\/\/saposyprincesas\" target=\"_blank\" rel=\"noopener noreferrer\">Sapos y Princesas<\/a> \/\u00a0<a title=\"Blogthinkbig.com\" href=\"https:\/\/blogthinkbig.com\/\" target=\"_blank\" rel=\"home noopener noreferrer\">Blogthinkbig<\/a>) que con su material han ayudado a realizar la siguiente publicaci\u00f3n. Esperamos que sean de ayuda para toda la comunidad docente y para las familias. No olviden que los experimentos que desean realizar, deben ser supervisados constantemente por un adulto.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/SfpVP0RavoI\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h5><strong>1. Masa magn\u00e9tica<\/strong><\/h5>\n<p style=\"text-align: justify;\">Un experimento que encantar\u00e1 a los ni\u00f1os es crear su propia masa y\u00a0<strong>hacer que reaccione ante la presencia de un im\u00e1n<\/strong>. Para la masa viscosa necesitas almid\u00f3n l\u00edquido pegamento escolar y un poco de polvo de \u00f3xido de hierro. Adem\u00e1s es bueno que tengas unos cuencos desechables y unos palitos de madera que luego puedas tirar. Para comenzar vierte 1\/4 de taza de almid\u00f3n l\u00edquido en un bol, a\u00f1ade 2 cucharadas de polvo de hierro y revuelve hasta que est\u00e9 bien mezclado. A\u00f1ade a tu mezcla 1\/4 de taza de pegamento escolar y revuelve.<\/p>\n<p style=\"text-align: justify;\">Una vez que la masa est\u00e9 viscosa es hora de empezar a mezclar con la mano. Lo m\u00e1s probable es que tus manos queden te\u00f1idas de negro por lo que es importante que se laven r\u00e1pido o que utilices guantes de l\u00e1tex. Elimina el exceso de l\u00edquido con una toallita de papel y deja secar. Una vez que est\u00e9 terminado ya no volver\u00e1 ensuciar. Ahora es el momento\u00a0<strong>hacer bailar la masa al comp\u00e1s del un im\u00e1n<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-9.jpg\" alt=\"\" width=\"930\" height=\"531\" \/><\/p>\n<h5><strong>2. Cascabeles en la botella<\/strong><\/h5>\n<p style=\"text-align: justify;\">Unos cascabeles pueden convertirse en un elemento perfecto para hacer experimentos con imanes. Solo necesitas meterlos\u00a0<strong>dentro de una botella de pl\u00e1stico<\/strong>\u00a0transparente y hacer que los ni\u00f1os jueguen a moverlos en su interior con una varilla magn\u00e9tica. Adem\u00e1s el movimiento crear\u00e1 el tintineo del cascabel. Otra modalidad de este juego es llenar la botella con agua y ver c\u00f3mo flotan en contacto con el im\u00e1n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36356\" src=\"http:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-10.jpg\" alt=\"\" width=\"926\" height=\"529\" srcset=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-10.jpg 700w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-10-300x171.jpg 300w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/p>\n<h5><strong>3. La fuerza de los imanes<\/strong><\/h5>\n<p style=\"text-align: justify;\">Puedes jugar con los ni\u00f1os a conocer la fuerza de distintos tipo de imanes de dos sencillas formas. En primer lugar puedes poner algunos objetos met\u00e1licos alineados en el suelo y frente a ellos imanes con diferentes fuerzas. Ve moviendo los imanes hasta descubrir\u00a0<strong>cu\u00e1ndo atrae cada uno al objeto que tiene enfrentado<\/strong>. Otra opci\u00f3n es colgar objetos de una cuerdecita que pegaremos al borde una mesa con cinta adhesiva. El objetivo es ver c\u00f3mo los distintos imanes hacen moverse el objeto sin llegar a tocarlo. Los m\u00e1s potentes podr\u00e1n hacer girar el metal hasta 360\u00ba.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36357\" src=\"http:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-11.jpg\" alt=\"\" width=\"915\" height=\"523\" srcset=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-11.jpg 700w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-11-300x171.jpg 300w\" sizes=\"auto, (max-width: 915px) 100vw, 915px\" \/><\/p>\n<h5><strong>4. Carreras de coches<\/strong><\/h5>\n<p style=\"text-align: justify;\">Puede parecer magia pero no. Es la reacci\u00f3n de los imanes que\u00a0 mueven los\u00a0cochecitos de juguete a trav\u00e9s de una pista que vosotros pod\u00e9is construir en casa. El experimento es muy sencillo. Todo lo que tienes que hacer es\u00a0<strong>pegar un im\u00e1n en la parte superior de un coche\u00a0<\/strong>de juguete con cinta adhesiva. Utiliza otro im\u00e1n, de polo inverso, para atraer el cochecito de juguete y hacer que corra sin necesidad de tocarlo. Una alternativa divertida es dar un coche a cada ni\u00f1o y que compitan entre ellos para ver qui\u00e9n llega primero a la meta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36358\" src=\"http:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-12.jpg\" alt=\"\" width=\"915\" height=\"523\" srcset=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-12.jpg 700w, https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-12-300x171.jpg 300w\" sizes=\"auto, (max-width: 915px) 100vw, 915px\" \/><\/p>\n<h5><strong>5. Tren casero<\/strong><\/h5>\n<p style=\"text-align: justify;\">Con tres elementos puedes crear tu propio tren casero. Necesitas una\u00a0<strong>pila AAA que ser\u00e1 el vag\u00f3n del tren, imanes potentes del mismo tama\u00f1o de la pila y un cable de cobre<\/strong>. Con ayuda de un palo haz una espiral con el cable de un di\u00e1metro similar al de la pila. Coloca los imanes en ambos extremos de la pila con los polos orientados en direcciones opuestas. Pon tu tren dentro del t\u00fanel de cobre. Ver\u00e1s como la pila se desplaza al existir una corriente el\u00e9ctrica que fluye a trav\u00e9s del cable. Esto crea un campo magn\u00e9tico que hace posible que el tren se mueva sin tocarlo.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/pk_IJ6GjmXI\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h4><strong>MAGNETISMO AVANZADO<\/strong><\/h4>\n<h5><strong>6. Pol\u00edgonos regulares: el efecto del magnetismo en el agua<\/strong><\/h5>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">El divulgador Manuel D\u00edaz Escalera dise\u00f1\u00f3 un sencillo experimento en el que se pod\u00edan comprobar las propiedades magn\u00e9ticas en el agua. Para demostrar este fen\u00f3meno f\u00edsico, utiliz\u00f3 fichas del conocido juego de las damas. Utilizando estas \u00abpiezas\u00bb, D\u00edaz Escalera ense\u00f1a c\u00f3mo el magnetismo provoca la formaci\u00f3n de pol\u00edgonos regulares sobre el agua, debido a las fuerzas de atracci\u00f3n y repulsi\u00f3n entre ellas:<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/aPkqflLmjrw\" width=\"100%\" height=\"600\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">Con este v\u00eddeo, se ve claramente c\u00f3mo el magnetismo tambi\u00e9n es capaz de actuar y \u00abmantenerse\u00bb dentro del agua. Esa es la raz\u00f3n por la que las fichas forman pol\u00edgonos regulares en el propio vaso con agua.<\/p>\n<h5><strong>7. El efecto magn\u00e9tico de \u00abralentizar\u00bb los movimientos<\/strong><\/h5>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">Imaginemos que intentamos introducir una pieza met\u00e1lica de\u00a0neodimio a trav\u00e9s de un tubo de cobre. \u00bfQu\u00e9 ocurrir\u00e1? El magnetismo es capaz de ralentizar su movimiento a trav\u00e9s del cilindro de cobre, algo que ya pens\u00f3 el f\u00edsico\u00a0<strong>Heinrich Friedrich Emil\u00a0Lenz<\/strong>, quien enunci\u00f3 la luego conocida como<strong> <a title=\"Ley de Lenz\" href=\"https:\/\/es.wikipedia.org\/wiki\/Ley_de_Lenz\" target=\"_blank\" rel=\"noopener noreferrer\">Ley de Lenz<\/a><\/strong>.<\/p>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">Esta teor\u00eda f\u00edsica fue determinada por el cient\u00edfico en 1833, y dice que \u00ab<em>e<\/em><i>l sentido de las corrientes o fuerza electromotriz inducida es tal que se opone siempre a la causa que la produce, o sea, a la variaci\u00f3n del flujo\u00bb.\u00a0<\/i>Como puede observarse en el v\u00eddeo, el paso de las piezas de neodimio se \u00abfrena\u00bb por un puro\u00a0<strong><a title=\"Magnetismo\" href=\"http:\/\/www.iflscience.com\/physics\/what-happens-when-you-drop-magnet-through-copper-tube\" target=\"_blank\" rel=\"noopener noreferrer\">efecto magn\u00e9tico<\/a><\/strong>.<\/p>\n<h5><strong>8. La Tierra, ese gran campo magn\u00e9tico<\/strong><\/h5>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">Cuando hablamos de magnetismo, no debemos olvidar que nuestro planeta se comporta como un gran im\u00e1n. Esta observaci\u00f3n fue realizada ya en 1600, cuando el f\u00edsico y fil\u00f3sofo brit\u00e1nico\u00a0<strong>William Gilbert<\/strong>\u00a0se\u00f1al\u00f3 esta similitud. El fen\u00f3meno magn\u00e9tico terrestre, no obstante, se usaba mucho tiempo atr\u00e1s, con el uso de las famosas br\u00fajulas en navegaci\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Ov7EWKk6MT8\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">Podemos comprobar a la perfecci\u00f3n c\u00f3mo funciona el magnetismo terrestre mediante el v\u00eddeo anterior. De nuevo el divulgador\u00a0D\u00edaz Escalera\u00a0muestra f\u00e1cilmente c\u00f3mo se comportar\u00eda el\u00a0<strong>campo magn\u00e9tico<\/strong>\u00a0interior de la bola de corcho (que funciona como si fuera el planeta Tierra). Las limaduras de hierro se sit\u00faan en funci\u00f3n de las l\u00edneas de fuerzas que salen del polo norte del im\u00e1n y entran por el polo sur de la bola de corcho.<\/p>\n<h5><strong>9. Trucos de magia que nos dejan \u00abmagnetizados\u00bb<\/strong><\/h5>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">El cuarto y \u00faltimo truco sobre magnetismo es, en realidad, una sencilla ilusi\u00f3n \u00f3ptica que nos ayuda a mezclar ciencia y magia. \u00bfEs posible apilar monedas utilizando tan s\u00f3lo su canto? El poder de los efectos magn\u00e9ticos es tan grande que podemos llegar realmente a \u00abhipnotizar\u00bb a nuestros oyentes con un pu\u00f1ado de monedas:<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/-LPeQ8Onbio\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p class=\"selectionShareable\" style=\"text-align: justify;\">La investigaci\u00f3n, y en especial \u00e1reas tan \u00abarduas\u00bb como la f\u00edsica, pueden ser divulgadas mediante\u00a0<strong>sencillos experimentos<\/strong>\u00a0como los citados. Aunque el magnetismo se conozca desde hace varios siglos, lo cierto es que es muy f\u00e1cil mostrar c\u00f3mo funciona este fen\u00f3meno f\u00edsico gracias a diversos trucos, haciendo que la docencia y el aprendizaje resulten menos complicados.<\/p>\n<h5><strong>11. Receta para preparar Slime magn\u00e9tica en tu casa<\/strong><\/h5>\n<p style=\"text-align: justify;\">Siguiendo estas instrucciones en alrededor de 20 minutos tendr\u00e1s una divertida slime magn\u00e9tica, para jugar hecha por ti mismo.<\/p>\n<p style=\"text-align: justify;\">Como podemos ver en el video los ingredientes que necesitas son:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Botella de resistol<\/li>\n<li style=\"text-align: justify;\">Agua<\/li>\n<li style=\"text-align: justify;\">Un Taz\u00f3n<\/li>\n<li style=\"text-align: justify;\">Borax en polvo (alg\u00fan detergente con b\u00f3rax)<\/li>\n<li style=\"text-align: justify;\">Limaduras de hierro<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Y posteriormente para jugar unos imanes.<\/p>\n<p style=\"text-align: justify;\">Para empezar a prepararla necesitas vaciar el pegamento en un taz\u00f3n y col\u00f3cale un poco de agua para vaciar quitar el pegamento que quedo en la botella.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone lazy-loaded\" src=\"https:\/\/media.giphy.com\/media\/XzuNAGNE88VLW\/giphy.gif\" alt=\"\" width=\"782\" height=\"440\" data-lazy-type=\"image\" data-lazy-src=\"https:\/\/media.giphy.com\/media\/XzuNAGNE88VLW\/giphy.gif\" \/><\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s haces una mezcla de agua con b\u00f3rax.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone lazy-loaded\" src=\"https:\/\/media.giphy.com\/media\/y0mdRHpmRYFEY\/200.gif\" alt=\"\" width=\"698\" height=\"392\" data-lazy-type=\"image\" data-lazy-src=\"https:\/\/media.giphy.com\/media\/y0mdRHpmRYFEY\/200.gif\" \/><\/p>\n<p style=\"text-align: justify;\">Agrega la soluci\u00f3n de b\u00f3rax al pegamento.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone lazy-loaded\" src=\"https:\/\/media.giphy.com\/media\/GE2Bzfflr9A1G\/200.gif\" alt=\"\" width=\"742\" height=\"417\" data-lazy-type=\"image\" data-lazy-src=\"https:\/\/media.giphy.com\/media\/GE2Bzfflr9A1G\/200.gif\" \/><\/p>\n<p style=\"text-align: justify;\">Y mezclala gradualmente hasta obtener el slime.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone lazy-loaded\" src=\"https:\/\/media.giphy.com\/media\/yaFA0lTF4GOFW\/200.gif\" alt=\"\" width=\"757\" height=\"425\" data-lazy-type=\"image\" data-lazy-src=\"https:\/\/media.giphy.com\/media\/yaFA0lTF4GOFW\/200.gif\" \/><\/p>\n<p style=\"text-align: justify;\">Para hacerla magn\u00e9tica agrega las limaduras de hierro e incorporalas mezclando.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone lazy-loaded\" src=\"https:\/\/media.giphy.com\/media\/Vw1uB7eKYJdhm\/200.gif\" alt=\"\" width=\"813\" height=\"457\" data-lazy-type=\"image\" data-lazy-src=\"https:\/\/media.giphy.com\/media\/Vw1uB7eKYJdhm\/200.gif\" \/><\/p>\n<p style=\"text-align: justify;\">Ahora si a divertirte jugando con los imanes.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone lazy-loaded\" src=\"https:\/\/media.giphy.com\/media\/j8kLLGVVn82DS\/200.gif\" alt=\"\" width=\"735\" height=\"413\" data-lazy-type=\"image\" data-lazy-src=\"https:\/\/media.giphy.com\/media\/j8kLLGVVn82DS\/200.gif\" \/><\/p>\n<p style=\"text-align: justify;\">Solo recuerda la versi\u00f3n casera del slime magn\u00e9tica se oxida as\u00ed que no podr\u00e1s usarla al d\u00eda siguiente.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone lazy-loaded\" src=\"https:\/\/media.giphy.com\/media\/cyowld1L9iOXe\/200.gif\" alt=\"\" width=\"767\" height=\"431\" data-lazy-type=\"image\" data-lazy-src=\"https:\/\/media.giphy.com\/media\/cyowld1L9iOXe\/200.gif\" \/><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/z9GJ6ILrHj0\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p>Les recordamos que todos estos experimentos deben ser supervisados siempre por un adulto.<\/p>\n<h3 class=\"p1\"><b>MATERIAL DE DESCARGA:<\/b><\/h3>\n<p class=\"p3\" style=\"text-align: center;\">\u00a1Comparte y as\u00ed m\u00e1s docentes utilizar\u00e1n estos recursos\u00a0gratis! Muchas gracias.<\/p>\n<p class=\"p4\" style=\"text-align: center;\"><span class=\"s1\" style=\"color: #000000;\"><b>DESCARGA: <a style=\"color: #000000;\" href=\"https:\/\/mega.nz\/#F!Oi5SECib!hvEU7X5gpQplb2WBliQmYw\" target=\"_blank\" rel=\"noopener noreferrer\">EXPERIMENTOS CIENT\u00cdFICOS PARA ENSE\u00d1AR \u00abMAGNETISMO\u00bb A LOS NI\u00d1OS<\/a><\/b><\/span><\/p>\n\t\t<div class=\"pk-inline-posts\">\n\t\t\t\n\t\t\t<div class=\"pk-inline-posts-container pk-inline-posts-template-list\"\n\t\t\t\tdata-columns=\"1\">\n\t\t\t\t\t\t<article id=\"post-119195\" class=\"post-119195 post type-post status-publish format-standard has-post-thumbnail category-descarga category-descargas-manuales-pdf category-dia-madre-y-padre category-pedagogia tag-actividades-educativas tag-creatividad-infantil tag-decoracion-escolar tag-dia-del-padre tag-manualidades-escolares tag-moldes-pdf tag-proyectos-escolares tag-recursos-educativos tag-tarjetas-para-papa cs-entry cs-video-wrap\">\n\t\t\t<div class=\"pk-post-outer\">\n\n\t\t\t\t\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<div class=\"entry-thumbnail\">\n\t\t\t\t\t\t<div class=\"pk-overlay pk-overlay-ratio pk-ratio-landscape\">\n\t\t\t\t\t\t\t<div class=\"pk-overlay-background\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/webdelmaestrocmf.com\/portal\/descarga-los-70-moldes-y-plantillas-para-el-dia-del-padre-un-recurso-creativo-que-ayuda-al-docente-a-ensenar-motivar-y-fortalecer-los-vinculos-familiares\/\" class=\"pk-overlay-link\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2026\/05\/1AA-Banner-1-portada-imagen-10-1-copia-1-14-300x225.webp\" class=\"attachment-pk-thumbnail size-pk-thumbnail wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<header>\n\t\t\t\t\t\t<h3 class=\"pk-title\"><a href=\"https:\/\/webdelmaestrocmf.com\/portal\/descarga-los-70-moldes-y-plantillas-para-el-dia-del-padre-un-recurso-creativo-que-ayuda-al-docente-a-ensenar-motivar-y-fortalecer-los-vinculos-familiares\/\" rel=\"bookmark\">Descarga los 70 moldes y plantillas para el D\u00eda del Padre: un recurso creativo que ayuda al docente a ense\u00f1ar, motivar y fortalecer los v\u00ednculos familiares<\/a><\/h3>\t\t\t\t\t<\/header><!-- .entry-header -->\n\t\t\t\t<\/div><!-- .post-inner -->\n\n\t\t\t<\/div><!-- .post-outer -->\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"Los\u00a0experimentos infantiles permiten a los ni\u00f1os aprender jugando. Por eso, nunca nos cansamos de presentar nuevos experimentos para&hellip;","protected":false},"author":1,"featured_media":44454,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"default","csco_page_header_type":"default","csco_page_load_nextpost":"default","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"csco_post_video_bg_volume":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2004,735],"tags":[685,3350,4713,4164,4238,297,4239],"class_list":{"0":"post-36352","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-descargas-manuales-pdf","8":"category-pedagogia","9":"tag-cientificos","10":"tag-experimentos","11":"tag-iman","12":"tag-magia","13":"tag-magnetismo","14":"tag-ninos","15":"tag-truos","16":"cs-entry","17":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar &quot;Magnetismo&quot; a los ni\u00f1os - 2026<\/title>\n<meta name=\"description\" content=\"El magnetismo es uno de los elementos que m\u00e1s magia tiene a los ojos de los ni\u00f1os. Este puede ser un buen punto de partida para\u00a0hacer experimentos...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar &quot;Magnetismo&quot; a los ni\u00f1os - 2026\" \/>\n<meta property=\"og:description\" content=\"El magnetismo es uno de los elementos que m\u00e1s magia tiene a los ojos de los ni\u00f1os. Este puede ser un buen punto de partida para\u00a0hacer experimentos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Web del Maestro CMF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WebdelMaestroCMF\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/WebdelMaestroCMF\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-18T21:30:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-18T21:39:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-110.jpg?fit=1100%2C680&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Web del Maestro CMF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cmf_w\" \/>\n<meta name=\"twitter:site\" content=\"@cmf_w\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ScholarlyArticle\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/\"},\"author\":{\"name\":\"Web del Maestro CMF\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/person\\\/1072a2ed7bd960df8ef99a551fa35dc5\"},\"headline\":\"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar \u00abMagnetismo\u00bb a los ni\u00f1os\",\"datePublished\":\"2020-02-18T21:30:08+00:00\",\"dateModified\":\"2020-02-18T21:39:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/\"},\"wordCount\":1511,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/1-110.jpg\",\"keywords\":[\"cient\u00edficos\",\"EXPERIMENTOS\",\"im\u00e1n\",\"MAGIA\",\"MAGNETISMO\",\"Ni\u00f1os\",\"TRUOS\"],\"articleSection\":[\"Descargas Manuales PDF\",\"Recursos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/\",\"name\":\"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar \\\"Magnetismo\\\" a los ni\u00f1os - 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/1-110.jpg\",\"datePublished\":\"2020-02-18T21:30:08+00:00\",\"dateModified\":\"2020-02-18T21:39:52+00:00\",\"description\":\"El magnetismo es uno de los elementos que m\u00e1s magia tiene a los ojos de los ni\u00f1os. Este puede ser un buen punto de partida para\u00a0hacer experimentos...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/1-110.jpg\",\"contentUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/1-110.jpg\",\"width\":1100,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recursos\",\"item\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/category\\\/pedagogia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar &#8220;Magnetismo&#8221; a los ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/\",\"name\":\"Web del Maestro CMF\",\"description\":\"Maestros al servicio de la educaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#organization\"},\"alternateName\":\"WMCMF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#organization\",\"name\":\"Web del Maestro CMF\",\"alternateName\":\"WMCMF\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-wmcmf-2.png\",\"contentUrl\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-wmcmf-2.png\",\"width\":200,\"height\":60,\"caption\":\"Web del Maestro CMF\"},\"image\":{\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WebdelMaestroCMF\\\/\",\"https:\\\/\\\/x.com\\\/cmf_w\",\"https:\\\/\\\/www.pinterest.com\\\/WMCMF\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/web-del-maestro-cmf\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wmcmf\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDPSvjbdodE5sHnC3OxutHw\",\"https:\\\/\\\/mastodon.social\\\/@wmcmf\",\"https:\\\/\\\/www.tiktok.com\\\/@webdelmaestrocmf\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/webdelmaestrocmf.com\\\/portal\\\/#\\\/schema\\\/person\\\/1072a2ed7bd960df8ef99a551fa35dc5\",\"name\":\"Web del Maestro CMF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g\",\"caption\":\"Web del Maestro CMF\"},\"description\":\"Esta Web se cre\u00f3 sin fines de lucro, con fines educativos, cient\u00edficos y acad\u00e9micos, para personas que tengan dificultades y\\\/o inconvenientes en visualizar el material original. El objetivo es entregar recursos, compartir experiencias y materiales que ayuden a los padres de familia, maestros y estudiantes en su actualizaci\u00f3n y formaci\u00f3n permanente, en bien de la Educaci\u00f3n.\",\"sameAs\":[\"http:\\\/\\\/webdelmaestrocmf.com\\\/portal\",\"https:\\\/\\\/www.facebook.com\\\/WebdelMaestroCMF\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wmcmf\\\/\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/web-del-maestro-cmf\",\"https:\\\/\\\/www.pinterest.com\\\/WMCMF\\\/publicaciones\\\/\",\"https:\\\/\\\/x.com\\\/cmf_w\",\"https:\\\/\\\/www.youtube.com\\\/@WMCMF\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar \"Magnetismo\" a los ni\u00f1os - 2026","description":"El magnetismo es uno de los elementos que m\u00e1s magia tiene a los ojos de los ni\u00f1os. Este puede ser un buen punto de partida para\u00a0hacer experimentos...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar \"Magnetismo\" a los ni\u00f1os - 2026","og_description":"El magnetismo es uno de los elementos que m\u00e1s magia tiene a los ojos de los ni\u00f1os. Este puede ser un buen punto de partida para\u00a0hacer experimentos...","og_url":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/","og_site_name":"Web del Maestro CMF","article_publisher":"https:\/\/www.facebook.com\/WebdelMaestroCMF\/","article_author":"https:\/\/www.facebook.com\/WebdelMaestroCMF\/","article_published_time":"2020-02-18T21:30:08+00:00","article_modified_time":"2020-02-18T21:39:52+00:00","og_image":[{"width":1100,"height":680,"url":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-110.jpg?fit=1100%2C680&ssl=1","type":"image\/jpeg"}],"author":"Web del Maestro CMF","twitter_card":"summary_large_image","twitter_creator":"@cmf_w","twitter_site":"@cmf_w","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ScholarlyArticle","@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#article","isPartOf":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/"},"author":{"name":"Web del Maestro CMF","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/person\/1072a2ed7bd960df8ef99a551fa35dc5"},"headline":"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar \u00abMagnetismo\u00bb a los ni\u00f1os","datePublished":"2020-02-18T21:30:08+00:00","dateModified":"2020-02-18T21:39:52+00:00","mainEntityOfPage":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/"},"wordCount":1511,"commentCount":0,"publisher":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#organization"},"image":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-110.jpg","keywords":["cient\u00edficos","EXPERIMENTOS","im\u00e1n","MAGIA","MAGNETISMO","Ni\u00f1os","TRUOS"],"articleSection":["Descargas Manuales PDF","Recursos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/","url":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/","name":"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar \"Magnetismo\" a los ni\u00f1os - 2026","isPartOf":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#primaryimage"},"image":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-110.jpg","datePublished":"2020-02-18T21:30:08+00:00","dateModified":"2020-02-18T21:39:52+00:00","description":"El magnetismo es uno de los elementos que m\u00e1s magia tiene a los ojos de los ni\u00f1os. Este puede ser un buen punto de partida para\u00a0hacer experimentos...","breadcrumb":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#primaryimage","url":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-110.jpg","contentUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-110.jpg","width":1100,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/webdelmaestrocmf.com\/portal\/experimentos-cientificos-para-ensenar-magnetismo-a-los-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/webdelmaestrocmf.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Recursos","item":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/"},{"@type":"ListItem","position":3,"name":"Fant\u00e1sticos experimentos y trucos de magia para ense\u00f1ar &#8220;Magnetismo&#8221; a los ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#website","url":"https:\/\/webdelmaestrocmf.com\/portal\/","name":"Web del Maestro CMF","description":"Maestros al servicio de la educaci\u00f3n","publisher":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#organization"},"alternateName":"WMCMF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/webdelmaestrocmf.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#organization","name":"Web del Maestro CMF","alternateName":"WMCMF","url":"https:\/\/webdelmaestrocmf.com\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/01\/logo-wmcmf-2.png","contentUrl":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/01\/logo-wmcmf-2.png","width":200,"height":60,"caption":"Web del Maestro CMF"},"image":{"@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WebdelMaestroCMF\/","https:\/\/x.com\/cmf_w","https:\/\/www.pinterest.com\/WMCMF\/","https:\/\/www.linkedin.com\/company\/web-del-maestro-cmf\/","https:\/\/www.instagram.com\/wmcmf\/","https:\/\/www.youtube.com\/channel\/UCDPSvjbdodE5sHnC3OxutHw","https:\/\/mastodon.social\/@wmcmf","https:\/\/www.tiktok.com\/@webdelmaestrocmf"]},{"@type":"Person","@id":"https:\/\/webdelmaestrocmf.com\/portal\/#\/schema\/person\/1072a2ed7bd960df8ef99a551fa35dc5","name":"Web del Maestro CMF","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23291dd5b5ae1077dcff3dbb04c3e02bd28403fa75af6d8787d5e97c5bbbe30b?s=96&d=mm&r=g","caption":"Web del Maestro CMF"},"description":"Esta Web se cre\u00f3 sin fines de lucro, con fines educativos, cient\u00edficos y acad\u00e9micos, para personas que tengan dificultades y\/o inconvenientes en visualizar el material original. El objetivo es entregar recursos, compartir experiencias y materiales que ayuden a los padres de familia, maestros y estudiantes en su actualizaci\u00f3n y formaci\u00f3n permanente, en bien de la Educaci\u00f3n.","sameAs":["http:\/\/webdelmaestrocmf.com\/portal","https:\/\/www.facebook.com\/WebdelMaestroCMF\/","https:\/\/www.instagram.com\/wmcmf\/","https:\/\/cl.linkedin.com\/company\/web-del-maestro-cmf","https:\/\/www.pinterest.com\/WMCMF\/publicaciones\/","https:\/\/x.com\/cmf_w","https:\/\/www.youtube.com\/@WMCMF"]}]}},"jetpack_featured_media_url":"https:\/\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2019\/05\/1-110.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":49336,"url":"https:\/\/webdelmaestrocmf.com\/portal\/70-experimentos-y-trucos-de-magia-para-ensenar-ciencia-en-casa\/","url_meta":{"origin":36352,"position":0},"title":"Cuadernillos de experimentos y magia para ense\u00f1ar ciencia","author":"Web del Maestro CMF","date":"21 julio, 2020","format":false,"excerpt":"Estudios recientes han demostrado que los ni\u00f1os piensan como cient\u00edficos. Es decir, su forma de razonar y experimentar (la elaboraci\u00f3n de hip\u00f3tesis y su comprobaci\u00f3n, a trav\u00e9s del m\u00e9todo del ensayo y error) se parece mucho a la que los investigadores emplean en el desarrollo de la ciencia. Por ese\u2026","rel":"","context":"En \u00abDescargas Manuales PDF\u00bb","block_context":{"text":"Descargas Manuales PDF","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/descargas-manuales-pdf\/"},"img":{"alt_text":"Experimentos","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/07\/2-25.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/07\/2-25.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/07\/2-25.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/07\/2-25.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/07\/2-25.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4533,"url":"https:\/\/webdelmaestrocmf.com\/portal\/canales-de-video-para-hacer-experimentos-educativos-en-la-casa-o-en-la-escuela\/","url_meta":{"origin":36352,"position":1},"title":"1000 gu\u00edas, manuales, im\u00e1genes y canales de v\u00eddeo para hacer experimentos educativos en la escuela","author":"Web del Maestro CMF","date":"28 marzo, 2022","format":false,"excerpt":"Generar expectativas en los alumnos es uno de los recursos pedag\u00f3gicos m\u00e1s entretenidos e impactantes que ocupan los docentes. Es entretenido porque se produce un momento m\u00e1gico, en donde los niveles de curiosidad de los estudiantes est\u00e1n al m\u00e1ximo. Es impactante porque, en ese instante, todo puede suceder. El aprendizaje\u2026","rel":"","context":"En \u00abDescargas Manuales PDF\u00bb","block_context":{"text":"Descargas Manuales PDF","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/descargas-manuales-pdf\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/03\/1-62.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/03\/1-62.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/03\/1-62.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/03\/1-62.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2020\/03\/1-62.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35561,"url":"https:\/\/webdelmaestrocmf.com\/portal\/55-experimentos-y-trucos-de-magia-para-ensenar-ciencia-en-la-escuela-y-en-casa\/","url_meta":{"origin":36352,"position":2},"title":"100 experimentos y trucos de magia para ense\u00f1ar ciencia","author":"Web del Maestro CMF","date":"12 enero, 2024","format":false,"excerpt":"Estudios recientes han demostrado que los ni\u00f1os piensan como cient\u00edficos. Es decir, su forma de razonar y experimentar (la elaboraci\u00f3n de hip\u00f3tesis y su comprobaci\u00f3n, a trav\u00e9s del m\u00e9todo del ensayo y error) se parece mucho a la que los investigadores emplean en el desarrollo de la ciencia. Por ese\u2026","rel":"","context":"En \u00abL\u00fadico\u00bb","block_context":{"text":"L\u00fadico","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/ludico\/"},"img":{"alt_text":"experimentos y trucos de magia para ense\u00f1ar ciencia","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/11\/Banner-1-portada-imagen-0-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/11\/Banner-1-portada-imagen-0-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/11\/Banner-1-portada-imagen-0-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/11\/Banner-1-portada-imagen-0-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":70410,"url":"https:\/\/webdelmaestrocmf.com\/portal\/libro-de-experimentos-de-ciencia-aprendemos-jugando\/","url_meta":{"origin":36352,"position":3},"title":"Libro de experimentos de Ciencia: Aprendemos jugando","author":"Web del Maestro CMF","date":"31 octubre, 2021","format":false,"excerpt":"La mejor manera de aprender es, sin duda, experimentando,\u00a0involucr\u00e1ndose con la materia que queremos aprender. Si nos limitamos a que los ni\u00f1os memoricen f\u00f3rmulas o realicen ejercicios, lo que podemos lograr es que lleguen a\u00a0desmotivarse\u00a0con las materias. Los experimentos cient\u00edficos consiguen\u00a0despertar el inter\u00e9s de los ni\u00f1os por la ciencia\u00a0y los\u2026","rel":"","context":"En \u00abLibros\u00bb","block_context":{"text":"Libros","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/libros\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/10\/1-140.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/10\/1-140.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/10\/1-140.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/10\/1-140.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2021\/10\/1-140.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":96371,"url":"https:\/\/webdelmaestrocmf.com\/portal\/cuadernillo-de-experimentos-para-ninos-de-primaria\/","url_meta":{"origin":36352,"position":4},"title":"Cuadernillo de experimentos para ni\u00f1os de primaria","author":"Web del Maestro CMF","date":"1 octubre, 2023","format":false,"excerpt":"En un mundo cada vez m\u00e1s digitalizado, es esencial fomentar la curiosidad y el inter\u00e9s por la ciencia desde una edad temprana. Los ni\u00f1os son naturalmente curiosos y ans\u00edan explorar el mundo que les rodea. Los experimentos cient\u00edficos para ni\u00f1os son una forma emocionante de nutrir esta curiosidad innata mientras\u2026","rel":"","context":"En \u00abCuadernillos\u00bb","block_context":{"text":"Cuadernillos","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/cuadernillos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/10\/A12B3C4D-60.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/10\/A12B3C4D-60.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/10\/A12B3C4D-60.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2023\/10\/A12B3C4D-60.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":78276,"url":"https:\/\/webdelmaestrocmf.com\/portal\/actividades-previas-a-la-escritura\/","url_meta":{"origin":36352,"position":5},"title":"Manual de actividades previas para promover la escritura","author":"Web del Maestro CMF","date":"7 julio, 2022","format":false,"excerpt":"Existen algunas actividades beneficiosas para desarrollar las habilidades previas a la escritura y que se pueden realizar en casa. Es necesario que tengas en cuenta estas actividades porque a tus hijos les ir\u00e1n muy bien para mejorar a nivel general. Por ello, a continuaci\u00f3n, vamos a darte algunas ideas de\u2026","rel":"","context":"En \u00abEscribir\u00bb","block_context":{"text":"Escribir","link":"https:\/\/webdelmaestrocmf.com\/portal\/category\/pedagogia\/escribir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/07\/Banner-1-portada-imagen-10-32.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/07\/Banner-1-portada-imagen-10-32.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/07\/Banner-1-portada-imagen-10-32.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/webdelmaestrocmf.com\/portal\/wp-content\/uploads\/2022\/07\/Banner-1-portada-imagen-10-32.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/posts\/36352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/comments?post=36352"}],"version-history":[{"count":0,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/posts\/36352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/media\/44454"}],"wp:attachment":[{"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/media?parent=36352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/categories?post=36352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webdelmaestrocmf.com\/portal\/wp-json\/wp\/v2\/tags?post=36352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}